{"id":4003,"date":"2018-07-31T16:43:01","date_gmt":"2018-07-31T13:43:01","guid":{"rendered":"https:\/\/cngspareparts.com\/?page_id=4003"},"modified":"2026-01-15T19:37:27","modified_gmt":"2026-01-15T16:37:27","slug":"1347234-cylinder-liner-144-dsc14-13-15__trashed","status":"publish","type":"product","link":"https:\/\/cngspareparts.com\/ru\/product\/1347234-cylinder-liner-144-dsc14-13-15__trashed\/","title":{"rendered":"1347234 CYLINDER LINER 144 DSC14 13 15"},"content":{"rendered":"<ul>\n<li><strong>OEM NO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0:<\/strong>1347234<\/li>\n<li><strong>CNG NO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 :<\/strong> DAF<\/li>\n<li><strong>DESCRIPTION\u00a0 :<\/strong>CYLINDER LINER<\/li>\n<li><strong>COMPATIBLE\u00a0 \u00a0:<\/strong>144 DSC14 13 15<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>OEM NO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0:1347234 CNG NO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 : DAF<\/p>","protected":false},"featured_media":3851,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[185,190],"product_tag":[3357,18471,6432,18472],"class_list":{"0":"post-4003","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-scania","7":"product_cat-scania-engine","8":"product_tag-1347234-cylinder-liner-144-dsc14-13-15","9":"product_tag-automotive-parts","10":"product_tag-scania-engine-spare-parts","11":"product_tag-turkey-automotive-parts-companies","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/product\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/comments?post=4003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/media\/3851"}],"wp:attachment":[{"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/product_brand?post=4003"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/product_cat?post=4003"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cngspareparts.com\/ru\/wp-json\/wp\/v2\/product_tag?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}